{"id":2601,"date":"2014-11-18T11:18:28","date_gmt":"2014-11-18T10:18:28","guid":{"rendered":"http:\/\/www.ribiskekarte.si\/blog\/?p=2601"},"modified":"2015-01-01T21:04:16","modified_gmt":"2015-01-01T20:04:16","slug":"la-guida-di-pesca-sul-fiume-ljubljanica-ap-barje","status":"publish","type":"post","link":"https:\/\/www.ribiskekarte.si\/blog\/la-guida-di-pesca-sul-fiume-ljubljanica-ap-barje\/","title":{"rendered":"La guida di pesca sul fiume Ljubljanica &#8211; AP Barje"},"content":{"rendered":"<p>Su fiume Ljubljanica \u00a0la pesca migliore e&#8217; dalla barca. Dalla costa potete pescare nel centro citt\u00e0 e dalli scalini di Ple\u010dnik in Trnovo. Se andate a pescare nella citt\u00e0 di Lubiana, potete lasciare la macchina sui i parcheggi pagabili. La seconda posizione per pescare e&#8217; di fronte la cassa dei pescatori di AP di Barje, li non potete lasciare la macchina. Per l&#8217; affitto della barca contattate l&#8217;\u00a0<a href=\"https:\/\/www.facebook.com\/rdbarje?fref=ts\">AP Barje su Facebook<\/a>, dove vi aiuteranno i membri della AP di Barje.<\/p>\n<p><a href=\"http:\/\/www.ribiskekarte.si\/blog\/wp-content\/uploads\/2014\/07\/IMGP3102abc.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-2219\" src=\"http:\/\/www.ribiskekarte.si\/blog\/wp-content\/uploads\/2014\/07\/IMGP3102abc-225x300.jpg\" alt=\"IMGP3102abc\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.ribiskekarte.si\/blog\/wp-content\/uploads\/2014\/07\/IMGP3102abc-225x300.jpg 225w, https:\/\/www.ribiskekarte.si\/blog\/wp-content\/uploads\/2014\/07\/IMGP3102abc.jpg 576w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><br \/>\nFoto: J. U\u0161eni\u010dnik<\/p>\n<p>La pesca sul fiume Ljubljanica e&#8217; molto difficoltosa, ma tutti i pescatori persistenti verranno regalati con bellissimi pesci. Le carpe sono attive durante l&#8217;estate e nell&#8217;autunno, bune esche sono il mais, boilies e polenta, anche qualche grosso verme. Le carpe si muovono in branchi. Proprio per questo un giorno la pesca e&#8217; buona, gia il prossimo giorno pu\u00f2 essere un disastro. Con l&#8217;\u00a0esche per carpe possiamo prendere qualche barbo o addirittura qualche trota fario. Pasturare qualche giorno prima non vi dar\u00e0 risultati. L&#8217;abboccate sono di solito molto forti e i pesci sono molto scattanti. Per questo e&#8217; un vero piacere pescare con una attrezzatura non troppo forte. Durante l&#8217;estate si pescano bene i barbi, pigi come esca vi consiglio di usare bigattini o pane.<\/p>\n<p>La pesca (spinnig) al luccio e molto imprevedibile e difficoltosa. I lucci sono in media grossi fra 70 e 80 cm, i luciperca sono molto rari. Non cosi rara e&#8217; l&#8217;abboccata di un salmone del Danubio (<em>hucho hucho<\/em>): per questo vi pregiamo che lo gentilmente rilasciate nel fiume. I lucci si trovano sul tutto il fiume, durante la pesca a spinning state molto attenti e cercate di usare esche varie (esche siliconice, pesciolini artificiali e jerk).<\/p>\n<p>Il fiume Ljubljanica e&#8217; largo fino 30 m e profondo fino 10 m, la profondit\u00e0 media e tra 5 fino 8 metri. Il flusso dell&#8217;acqua migliore per la pesca (livello dell&#8217;acqua) e tra 10 e 50 kb\/s. Tutto di sopra questi numeri non e&#8217; pi\u00f9 adatto per una pesca comoda. Se decidete di andare di pescare dalla barca vi consiglio di prendere con se abbastanza acqua da bere e di essere ben protetti dal sole.<\/p>\n<figure id=\"attachment_2139\" aria-describedby=\"caption-attachment-2139\" style=\"width: 300px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.ribiskekarte.si\/blog\/wp-content\/uploads\/2014\/07\/10341632_880786325281493_9093795238965960888_n.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-2139\" src=\"http:\/\/www.ribiskekarte.si\/blog\/wp-content\/uploads\/2014\/07\/10341632_880786325281493_9093795238965960888_n-300x225.jpg\" alt=\"\u0160\u010duka iz Ljubljanice. Foto: \u017d. Tadi\u010d\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.ribiskekarte.si\/blog\/wp-content\/uploads\/2014\/07\/10341632_880786325281493_9093795238965960888_n-300x225.jpg 300w, https:\/\/www.ribiskekarte.si\/blog\/wp-content\/uploads\/2014\/07\/10341632_880786325281493_9093795238965960888_n.jpg 960w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-2139\" class=\"wp-caption-text\">Luccio da Ljubljanica. Foto: \u017d. Tadi\u010d<\/figcaption><\/figure>\n<p>I permessi di pesca li potete comprare qui: <a href=\"http:\/\/www.ribiskekarte.si\/it\/rd-barje\/reka-Ljubljanica-barje\" target=\"_blank\">www.ribiskekarte.si\/it\/rd-barje\/reka-Ljubljanica-barje<\/a><\/p>\n<p>Per pi\u00f9 informazioni contattaci: info@ribiskekarte.si o\u00a0<a href=\"http:\/\/www.ribiskekarte.si\/it\/kontakt\" target=\"_blank\">http:\/\/www.ribiskekarte.si\/it\/kontakt<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Su fiume Ljubljanica \u00a0la pesca migliore e&#8217; dalla barca. Dalla costa potete pescare nel centro citt\u00e0 e dalli scalini di<\/p>\n","protected":false},"author":8,"featured_media":2691,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[6],"tags":[],"class_list":["post-2601","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prispevki"],"_links":{"self":[{"href":"https:\/\/www.ribiskekarte.si\/blog\/wp-json\/wp\/v2\/posts\/2601","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ribiskekarte.si\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ribiskekarte.si\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ribiskekarte.si\/blog\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ribiskekarte.si\/blog\/wp-json\/wp\/v2\/comments?post=2601"}],"version-history":[{"count":9,"href":"https:\/\/www.ribiskekarte.si\/blog\/wp-json\/wp\/v2\/posts\/2601\/revisions"}],"predecessor-version":[{"id":2610,"href":"https:\/\/www.ribiskekarte.si\/blog\/wp-json\/wp\/v2\/posts\/2601\/revisions\/2610"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ribiskekarte.si\/blog\/wp-json\/wp\/v2\/media\/2691"}],"wp:attachment":[{"href":"https:\/\/www.ribiskekarte.si\/blog\/wp-json\/wp\/v2\/media?parent=2601"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ribiskekarte.si\/blog\/wp-json\/wp\/v2\/categories?post=2601"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ribiskekarte.si\/blog\/wp-json\/wp\/v2\/tags?post=2601"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}